{"id":169,"date":"2015-05-25T13:21:28","date_gmt":"2015-05-25T12:21:28","guid":{"rendered":"http:\/\/shglb.iftsn.com\/?p=169"},"modified":"2015-05-25T13:23:40","modified_gmt":"2015-05-25T12:23:40","slug":"le-moulin-du-lot-190","status":"publish","type":"post","link":"https:\/\/shglb.com\/index.php\/2015\/05\/25\/le-moulin-du-lot-190\/","title":{"rendered":"Le moulin du lot 190"},"content":{"rendered":"<p>On sait qu\u2019il existait d\u00e9j\u00e0 un moulin \u00e0 scie sur le lot 190, en 1871, gr\u00e2ce \u00e0 un acte notari\u00e9 du 27 d\u00e9cembre 1871. Lubin Barab\u00e9 donnait en garantie pour un pr\u00eat, un terrain d\u2019environ 20 arpents en superficie avec moulin \u00e0 scie et autres b\u00e2tisses \u00e9rig\u00e9es, faisant partie du lot 190. Ce lot avait ceci de particulier, qu\u2019il \u00e9tait enclav\u00e9 au milieu des terres, et qu\u2019il communiquait avec le chemin du troisi\u00e8me rang, et celui d\u2019En-haut, par des bandes de terre de la largeur d\u2019une vingtaine de pieds.<\/p>\n<p>Puis, en 1874, Lubin Barab\u00e9 vendait \u00e0 son fr\u00e8re Eustache, pour $200.00, la partie nord du lot 190, \u00ab avec dessus construit un moulin \u00e0 bardeaux avec toutes les appartenances et d\u00e9pendances, tel et ainsi que le terrain se trouve et que l\u2019acqu\u00e9reur dit bien conna\u00eetre, l\u2019ayant vu et visit\u00e9 et dit en \u00eatre content et satisfait \u00bb. La chauss\u00e9e (le barrage) devait dor\u00e9navant \u00eatre entretenue \u00e0 parts \u00e9gales, et les deux fr\u00e8res s\u2019obligeaient \u00e0 \u00ab s\u2019entendre dans les eaux basses pour prendre d\u2019\u00e9galit\u00e9 leur tour par l\u2019\u00e9clusage de la dite chauss\u00e9e pour faire marcher chacun leur moulin \u00bb.<\/p>\n<p>A son tour, Eustache Barab\u00e9 vend en 1883, pour $400.00, sa propre partie (nord) du lot 190, \u00e0 \u00c9vang\u00e9liste Roberge, meunier de Sainte-Sophie, qui sera tenu aux m\u00eames obligations d\u2019entretien de la chauss\u00e9e.<\/p>\n<p>Puis, en 1884, Lubin Barab\u00e9 c\u00e8de \u00e0 Joseph Lavall\u00e9e pour $800.00, la partie sud du lot 190. On suppose que la partie nord du lot a aussi \u00e9t\u00e9 acquise par Joseph Lavall\u00e9e, mais que le contrat de vente n\u2019a pas \u00e9t\u00e9 enregistr\u00e9, comme il arrivait \u00e0 l\u2019occasion, \u00e0 cette \u00e9poque. En effet, en 1898, Joseph Lavall\u00e9e donne tous ses biens, comprenant tout le lot 190, \u00e0 son fils Henri, mais un an plus tard, celui-ci r\u00e9troc\u00e8de le tout \u00e0 son p\u00e8re.<\/p>\n<p>Puis, en 1899, le lot et ses moulins seront vendus aux ench\u00e8res, pour $110.00 \u00e0 la porte de l\u2019\u00e9glise de Saint-Pierre-les-Becquets, par le sh\u00e9rif Charles Dumoulin. L\u2019acqu\u00e9reur est Th\u00e9odore Jacques, mais celui-ci, quatre mois plus tard, vend le tout pour $250.00 \u00e0 dame Henriette Baril, veuve de Cyrille Gervais, qui elle-m\u00eame, en mai 1900, c\u00e8de la partie sud du lot \u00e0 Alph\u00e9rie Paquin, pour la modeste somme de $50.00, mais conserve sa partie nord pour la donner \u00e0 son fils Alfred en 1908.<\/p>\n<p>Un demi-si\u00e8cle plus tard, en 1953, dame Florida Neault, veuve d\u2019Alfred Gervais, donne \u00e0 son fils Marcel la partie nord du lot, qui sera acquise plus tard par Joseph Durrer.<\/p>\n<p>Quant \u00e0 la partie sud, elle appartient d\u00e9sormais \u00e0 Jacques Delisle, de Sainte-C\u00e9cile-de-L\u00e9vrard.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>On sait qu\u2019il existait d\u00e9j\u00e0 un moulin \u00e0 scie sur le lot 190, en 1871, gr\u00e2ce \u00e0 un acte notari\u00e9 du 27 d\u00e9cembre 1871. Lubin Barab\u00e9 donnait en garantie pour un pr\u00eat, un terrain d\u2019environ 20 arpents en superficie avec moulin \u00e0 scie et autres b\u00e2tisses \u00e9rig\u00e9es, faisant partie du lot 190. Ce lot avait [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-169","post","type-post","status-publish","format-standard","hentry","category-les-moulins"],"_links":{"self":[{"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/posts\/169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/comments?post=169"}],"version-history":[{"count":1,"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/posts\/169\/revisions"}],"predecessor-version":[{"id":170,"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/posts\/169\/revisions\/170"}],"wp:attachment":[{"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/media?parent=169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/categories?post=169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shglb.com\/index.php\/wp-json\/wp\/v2\/tags?post=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}